{"id":11711,"count":25,"description":"","link":"https:\/\/lorrtec-racing-parts.com\/es\/product_util\/auto-es\/porsche-es\/996-997-es\/","name":"996\/997","slug":"996-997-es","taxonomy":"product_util","parent":11684,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pi\u00e8ces moteur pour Porsche 996\/997 - Lorrtec Racing Parts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lorrtec-racing-parts.com\/es\/product_util\/auto-es\/porsche-es\/996-997-es\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pi\u00e8ces moteur pour Porsche 996\/997 - Lorrtec Racing Parts\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lorrtec-racing-parts.com\/es\/product_util\/auto-es\/porsche-es\/996-997-es\/\" \/>\n<meta property=\"og:site_name\" content=\"Lorrtec Racing Parts\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/lorrtec-racing-parts.com\\\/es\\\/product_util\\\/auto-es\\\/porsche-es\\\/996-997-es\\\/\",\"url\":\"https:\\\/\\\/lorrtec-racing-parts.com\\\/es\\\/product_util\\\/auto-es\\\/porsche-es\\\/996-997-es\\\/\",\"name\":\"Pi\u00e8ces moteur pour Porsche 996\\\/997 - Lorrtec Racing Parts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lorrtec-racing-parts.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lorrtec-racing-parts.com\\\/es\\\/product_util\\\/auto-es\\\/porsche-es\\\/996-997-es\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lorrtec-racing-parts.com\\\/es\\\/product_util\\\/auto-es\\\/porsche-es\\\/996-997-es\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lorrtec-racing-parts.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AUTO\",\"item\":\"https:\\\/\\\/lorrtec-racing-parts.com\\\/es\\\/product_util\\\/auto-es\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"PORSCHE\",\"item\":\"https:\\\/\\\/lorrtec-racing-parts.com\\\/es\\\/product_util\\\/auto-es\\\/porsche-es\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"996\\\/997\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lorrtec-racing-parts.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/lorrtec-racing-parts.com\\\/es\\\/\",\"name\":\"Lorrtec Racing Parts\",\"description\":\"Le sp\u00e9cialiste de la pi\u00e8ce moteur\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lorrtec-racing-parts.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pi\u00e8ces moteur pour Porsche 996\/997 - Lorrtec Racing Parts","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lorrtec-racing-parts.com\/es\/product_util\/auto-es\/porsche-es\/996-997-es\/","og_locale":"es_ES","og_type":"article","og_title":"Pi\u00e8ces moteur pour Porsche 996\/997 - Lorrtec Racing Parts","og_url":"https:\/\/lorrtec-racing-parts.com\/es\/product_util\/auto-es\/porsche-es\/996-997-es\/","og_site_name":"Lorrtec Racing Parts","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/lorrtec-racing-parts.com\/es\/product_util\/auto-es\/porsche-es\/996-997-es\/","url":"https:\/\/lorrtec-racing-parts.com\/es\/product_util\/auto-es\/porsche-es\/996-997-es\/","name":"Pi\u00e8ces moteur pour Porsche 996\/997 - Lorrtec Racing Parts","isPartOf":{"@id":"https:\/\/lorrtec-racing-parts.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/lorrtec-racing-parts.com\/es\/product_util\/auto-es\/porsche-es\/996-997-es\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/lorrtec-racing-parts.com\/es\/product_util\/auto-es\/porsche-es\/996-997-es\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lorrtec-racing-parts.com\/es\/"},{"@type":"ListItem","position":2,"name":"AUTO","item":"https:\/\/lorrtec-racing-parts.com\/es\/product_util\/auto-es\/"},{"@type":"ListItem","position":3,"name":"PORSCHE","item":"https:\/\/lorrtec-racing-parts.com\/es\/product_util\/auto-es\/porsche-es\/"},{"@type":"ListItem","position":4,"name":"996\/997"}]},{"@type":"WebSite","@id":"https:\/\/lorrtec-racing-parts.com\/es\/#website","url":"https:\/\/lorrtec-racing-parts.com\/es\/","name":"Lorrtec Racing Parts","description":"Le sp\u00e9cialiste de la pi\u00e8ce moteur","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lorrtec-racing-parts.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/lorrtec-racing-parts.com\/es\/wp-json\/wp\/v2\/product_util\/11711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lorrtec-racing-parts.com\/es\/wp-json\/wp\/v2\/product_util"}],"about":[{"href":"https:\/\/lorrtec-racing-parts.com\/es\/wp-json\/wp\/v2\/taxonomies\/product_util"}],"up":[{"embeddable":true,"href":"https:\/\/lorrtec-racing-parts.com\/es\/wp-json\/wp\/v2\/product_util\/11684"}],"wp:post_type":[{"href":"https:\/\/lorrtec-racing-parts.com\/es\/wp-json\/wp\/v2\/product?product_util=11711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}